<br />
<b>Warning</b>:  Trying to access array offset on value of type null in <b>D:\inetpub\webs\felicedellacortecom\wp-content\themes\polite\templatesell\filters\excerpt.php</b> on line <b>29</b><br />
<br />
<b>Warning</b>:  Trying to access array offset on value of type null in <b>D:\inetpub\webs\felicedellacortecom\wp-content\themes\polite\templatesell\filters\excerpt.php</b> on line <b>29</b><br />
<br />
<b>Warning</b>:  Trying to access array offset on value of type null in <b>D:\inetpub\webs\felicedellacortecom\wp-content\themes\polite\templatesell\filters\excerpt.php</b> on line <b>29</b><br />
{"id":41,"date":"2012-04-12T14:07:46","date_gmt":"2012-04-12T12:07:46","guid":{"rendered":"https:\/\/www.felicedellacorte.com\/?p=41"},"modified":"2021-04-12T23:14:41","modified_gmt":"2021-04-12T21:14:41","slug":"2012-sedia-sediola","status":"publish","type":"post","link":"http:\/\/www.felicedellacorte.com\/index.php\/2012-sedia-sediola\/","title":{"rendered":"2012 &#8211; SEDIA SEDIOLA"},"content":{"rendered":"\n<p class=\"has-medium-font-size wp-block-paragraph\"><em>di Rosario Galli<\/em><br>Attore protagonista con Nathalie Caldonazzo<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">con Nathalie CALDONAZZO, Felice DELLA CORTE<br>Gabriele CAPPARUCCI, Teresa DI GENNARO, Ludovica BEI<br>Regia di Claudio BOCCACCINI<br>(Fotografie di Valerio Faccini)<\/p>\n\n\n<style type=\"text\/css\">\n#foogallery-gallery-297 .fg-image { width: 150px; }\n#foogallery-gallery-297 { --fg-gutter: 10px; }<\/style>\n\t\t\t<div class=\"foogallery foogallery-container foogallery-default foogallery-lightbox-foobox fg-center fg-default fg-ready fg-light fg-border-thin fg-shadow-outline fg-loading-default fg-loaded-fade-in fg-caption-hover fg-hover-fade fg-hover-zoom\" id=\"foogallery-gallery-297\" data-foogallery=\"{&quot;item&quot;:{&quot;showCaptionTitle&quot;:true,&quot;showCaptionDescription&quot;:true},&quot;lazy&quot;:true,&quot;src&quot;:&quot;src&quot;,&quot;srcset&quot;:&quot;srcset&quot;}\" style=\"--fg-title-line-clamp: 0; --fg-description-line-clamp: 0;\" >\n\t<div class=\"fg-item fg-type-image fg-loading\"><figure class=\"fg-item-inner\"><a href=\"http:\/\/www.felicedellacorte.com\/wp-content\/uploads\/2021\/04\/1-9.jpg\" data-attachment-id=\"298\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img src=\"http:\/\/www.felicedellacorte.com\/wp-content\/uploads\/cache\/2021\/04\/1-9\/164322742.jpg\" width=\"150\" height=\"150\" class=\"skip-lazy fg-image\" decoding=\"async\" loading=\"lazy\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-loading\"><figure class=\"fg-item-inner\"><a href=\"http:\/\/www.felicedellacorte.com\/wp-content\/uploads\/2021\/04\/2-9.jpg\" data-attachment-id=\"299\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img src=\"http:\/\/www.felicedellacorte.com\/wp-content\/uploads\/cache\/2021\/04\/2-9\/2000358949.jpg\" width=\"150\" height=\"150\" class=\"skip-lazy fg-image\" decoding=\"async\" loading=\"lazy\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-loading\"><figure class=\"fg-item-inner\"><a href=\"http:\/\/www.felicedellacorte.com\/wp-content\/uploads\/2021\/04\/3-9.jpg\" data-attachment-id=\"300\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img src=\"http:\/\/www.felicedellacorte.com\/wp-content\/uploads\/cache\/2021\/04\/3-9\/-1103412782.jpg\" width=\"150\" height=\"150\" class=\"skip-lazy fg-image\" decoding=\"async\" loading=\"lazy\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-loading\"><figure class=\"fg-item-inner\"><a href=\"http:\/\/www.felicedellacorte.com\/wp-content\/uploads\/2021\/04\/4-9.jpg\" data-attachment-id=\"301\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img src=\"http:\/\/www.felicedellacorte.com\/wp-content\/uploads\/cache\/2021\/04\/4-9\/-920604101.jpg\" width=\"150\" height=\"150\" class=\"skip-lazy fg-image\" decoding=\"async\" loading=\"lazy\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-loading\"><figure class=\"fg-item-inner\"><a href=\"http:\/\/www.felicedellacorte.com\/wp-content\/uploads\/2021\/04\/5-9.jpg\" data-attachment-id=\"302\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img src=\"http:\/\/www.felicedellacorte.com\/wp-content\/uploads\/cache\/2021\/04\/5-9\/1138484980.jpg\" width=\"150\" height=\"150\" class=\"skip-lazy fg-image\" decoding=\"async\" loading=\"lazy\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-loading\"><figure class=\"fg-item-inner\"><a href=\"http:\/\/www.felicedellacorte.com\/wp-content\/uploads\/2021\/04\/6-9.jpg\" data-attachment-id=\"303\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img src=\"http:\/\/www.felicedellacorte.com\/wp-content\/uploads\/cache\/2021\/04\/6-9\/1026274663.jpg\" width=\"150\" height=\"150\" class=\"skip-lazy fg-image\" decoding=\"async\" loading=\"lazy\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-loading\"><figure class=\"fg-item-inner\"><a href=\"http:\/\/www.felicedellacorte.com\/wp-content\/uploads\/2021\/04\/7-9.jpg\" data-attachment-id=\"304\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img src=\"http:\/\/www.felicedellacorte.com\/wp-content\/uploads\/cache\/2021\/04\/7-9\/-1923331797.jpg\" width=\"150\" height=\"150\" class=\"skip-lazy fg-image\" decoding=\"async\" loading=\"lazy\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-loading\"><figure class=\"fg-item-inner\"><a href=\"http:\/\/www.felicedellacorte.com\/wp-content\/uploads\/2021\/04\/8-9.jpg\" data-attachment-id=\"305\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img src=\"http:\/\/www.felicedellacorte.com\/wp-content\/uploads\/cache\/2021\/04\/8-9\/-376374730.jpg\" width=\"150\" height=\"150\" class=\"skip-lazy fg-image\" decoding=\"async\" loading=\"lazy\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-loading\"><figure class=\"fg-item-inner\"><a href=\"http:\/\/www.felicedellacorte.com\/wp-content\/uploads\/2021\/04\/9-9.jpg\" data-attachment-id=\"306\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img src=\"http:\/\/www.felicedellacorte.com\/wp-content\/uploads\/cache\/2021\/04\/9-9\/1668001529.jpg\" width=\"150\" height=\"150\" class=\"skip-lazy fg-image\" decoding=\"async\" loading=\"lazy\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-loading\"><figure class=\"fg-item-inner\"><a href=\"http:\/\/www.felicedellacorte.com\/wp-content\/uploads\/2021\/04\/10-9.jpg\" data-attachment-id=\"307\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img src=\"http:\/\/www.felicedellacorte.com\/wp-content\/uploads\/cache\/2021\/04\/10-9\/1071115144.jpg\" width=\"150\" height=\"150\" class=\"skip-lazy fg-image\" decoding=\"async\" loading=\"lazy\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><\/figure><div class=\"fg-loader\"><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>di Rosario GalliAttore protagonista con Nathalie Caldonazzo con Nathalie CALDONAZZO, Felice DELLA CORTEGabriele CAPPARUCCI, Teresa DI GENNARO, Ludovica BEIRegia di Claudio BOCCACCINI(Fotografie di Valerio Faccini)<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[5],"tags":[],"class_list":["post-41","post","type-post","status-publish","format-standard","hentry","category-spettacoli"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>2012 - SEDIA SEDIOLA - Felice Della Corte<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"http:\/\/www.felicedellacorte.com\/index.php\/2012-sedia-sediola\/\" \/>\r\n<meta property=\"og:locale\" content=\"it_IT\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"2012 - SEDIA SEDIOLA - Felice Della Corte\" \/>\r\n<meta property=\"og:description\" content=\"di Rosario GalliAttore protagonista con Nathalie Caldonazzo con Nathalie CALDONAZZO, Felice DELLA CORTEGabriele CAPPARUCCI, Teresa DI GENNARO, Ludovica BEIRegia di Claudio BOCCACCINI(Fotografie di Valerio Faccini)\" \/>\r\n<meta property=\"og:url\" content=\"http:\/\/www.felicedellacorte.com\/index.php\/2012-sedia-sediola\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Felice Della Corte\" \/>\r\n<meta property=\"article:published_time\" content=\"2012-04-12T12:07:46+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2021-04-12T21:14:41+00:00\" \/>\r\n<meta name=\"author\" content=\"DavidC\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.felicedellacorte.com\\\/index.php\\\/2012-sedia-sediola\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.felicedellacorte.com\\\/index.php\\\/2012-sedia-sediola\\\/\"},\"author\":{\"name\":\"DavidC\",\"@id\":\"http:\\\/\\\/www.felicedellacorte.com\\\/#\\\/schema\\\/person\\\/9f35bb5ac75d5d60498bc497f8bc2793\"},\"headline\":\"2012 &#8211; SEDIA SEDIOLA\",\"datePublished\":\"2012-04-12T12:07:46+00:00\",\"dateModified\":\"2021-04-12T21:14:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.felicedellacorte.com\\\/index.php\\\/2012-sedia-sediola\\\/\"},\"wordCount\":30,\"commentCount\":0,\"articleSection\":[\"SPETTACOLI\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/www.felicedellacorte.com\\\/index.php\\\/2012-sedia-sediola\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.felicedellacorte.com\\\/index.php\\\/2012-sedia-sediola\\\/\",\"url\":\"http:\\\/\\\/www.felicedellacorte.com\\\/index.php\\\/2012-sedia-sediola\\\/\",\"name\":\"2012 - SEDIA SEDIOLA - Felice Della Corte\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.felicedellacorte.com\\\/#website\"},\"datePublished\":\"2012-04-12T12:07:46+00:00\",\"dateModified\":\"2021-04-12T21:14:41+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/www.felicedellacorte.com\\\/#\\\/schema\\\/person\\\/9f35bb5ac75d5d60498bc497f8bc2793\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.felicedellacorte.com\\\/index.php\\\/2012-sedia-sediola\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.felicedellacorte.com\\\/index.php\\\/2012-sedia-sediola\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.felicedellacorte.com\\\/index.php\\\/2012-sedia-sediola\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/www.felicedellacorte.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"2012 &#8211; SEDIA SEDIOLA\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/www.felicedellacorte.com\\\/#website\",\"url\":\"http:\\\/\\\/www.felicedellacorte.com\\\/\",\"name\":\"Felice Della Corte\",\"description\":\"Attore e Regista Teatrale. \",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/www.felicedellacorte.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/www.felicedellacorte.com\\\/#\\\/schema\\\/person\\\/9f35bb5ac75d5d60498bc497f8bc2793\",\"name\":\"DavidC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bdee4b92b5e79b440a0d67bda09813e2053bfae88e38b4250dd1316a22eea732?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bdee4b92b5e79b440a0d67bda09813e2053bfae88e38b4250dd1316a22eea732?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bdee4b92b5e79b440a0d67bda09813e2053bfae88e38b4250dd1316a22eea732?s=96&d=mm&r=g\",\"caption\":\"DavidC\"},\"sameAs\":[\"http:\\\/\\\/www.felicedellacorte.com\"],\"url\":\"http:\\\/\\\/www.felicedellacorte.com\\\/index.php\\\/author\\\/davidc\\\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"2012 - SEDIA SEDIOLA - Felice Della Corte","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.felicedellacorte.com\/index.php\/2012-sedia-sediola\/","og_locale":"it_IT","og_type":"article","og_title":"2012 - SEDIA SEDIOLA - Felice Della Corte","og_description":"di Rosario GalliAttore protagonista con Nathalie Caldonazzo con Nathalie CALDONAZZO, Felice DELLA CORTEGabriele CAPPARUCCI, Teresa DI GENNARO, Ludovica BEIRegia di Claudio BOCCACCINI(Fotografie di Valerio Faccini)","og_url":"http:\/\/www.felicedellacorte.com\/index.php\/2012-sedia-sediola\/","og_site_name":"Felice Della Corte","article_published_time":"2012-04-12T12:07:46+00:00","article_modified_time":"2021-04-12T21:14:41+00:00","author":"DavidC","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":false,"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.felicedellacorte.com\/index.php\/2012-sedia-sediola\/#article","isPartOf":{"@id":"http:\/\/www.felicedellacorte.com\/index.php\/2012-sedia-sediola\/"},"author":{"name":"DavidC","@id":"http:\/\/www.felicedellacorte.com\/#\/schema\/person\/9f35bb5ac75d5d60498bc497f8bc2793"},"headline":"2012 &#8211; SEDIA SEDIOLA","datePublished":"2012-04-12T12:07:46+00:00","dateModified":"2021-04-12T21:14:41+00:00","mainEntityOfPage":{"@id":"http:\/\/www.felicedellacorte.com\/index.php\/2012-sedia-sediola\/"},"wordCount":30,"commentCount":0,"articleSection":["SPETTACOLI"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/www.felicedellacorte.com\/index.php\/2012-sedia-sediola\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/www.felicedellacorte.com\/index.php\/2012-sedia-sediola\/","url":"http:\/\/www.felicedellacorte.com\/index.php\/2012-sedia-sediola\/","name":"2012 - SEDIA SEDIOLA - Felice Della Corte","isPartOf":{"@id":"http:\/\/www.felicedellacorte.com\/#website"},"datePublished":"2012-04-12T12:07:46+00:00","dateModified":"2021-04-12T21:14:41+00:00","author":{"@id":"http:\/\/www.felicedellacorte.com\/#\/schema\/person\/9f35bb5ac75d5d60498bc497f8bc2793"},"breadcrumb":{"@id":"http:\/\/www.felicedellacorte.com\/index.php\/2012-sedia-sediola\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.felicedellacorte.com\/index.php\/2012-sedia-sediola\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/www.felicedellacorte.com\/index.php\/2012-sedia-sediola\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/www.felicedellacorte.com\/"},{"@type":"ListItem","position":2,"name":"2012 &#8211; SEDIA SEDIOLA"}]},{"@type":"WebSite","@id":"http:\/\/www.felicedellacorte.com\/#website","url":"http:\/\/www.felicedellacorte.com\/","name":"Felice Della Corte","description":"Attore e Regista Teatrale. ","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.felicedellacorte.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"http:\/\/www.felicedellacorte.com\/#\/schema\/person\/9f35bb5ac75d5d60498bc497f8bc2793","name":"DavidC","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/bdee4b92b5e79b440a0d67bda09813e2053bfae88e38b4250dd1316a22eea732?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bdee4b92b5e79b440a0d67bda09813e2053bfae88e38b4250dd1316a22eea732?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bdee4b92b5e79b440a0d67bda09813e2053bfae88e38b4250dd1316a22eea732?s=96&d=mm&r=g","caption":"DavidC"},"sameAs":["http:\/\/www.felicedellacorte.com"],"url":"http:\/\/www.felicedellacorte.com\/index.php\/author\/davidc\/"}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"polite-thumbnail-size":false,"polite-related-size":false,"polite-promo-post":false,"polite-related-post-thumbnails":false},"uagb_author_info":{"display_name":false,"author_link":"http:\/\/www.felicedellacorte.com\/index.php\/author\/davidc\/"},"uagb_comment_info":0,"uagb_excerpt":"di Rosario GalliAttore protagonista con Nathalie Caldonazzo con Nathalie CALDONAZZO, Felice DELLA CORTEGabriele CAPPARUCCI, Teresa DI GENNARO, Ludovica BEIRegia di Claudio BOCCACCINI(Fotografie di Valerio Faccini)","_links":{"self":[{"href":"http:\/\/www.felicedellacorte.com\/index.php\/wp-json\/wp\/v2\/posts\/41","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.felicedellacorte.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.felicedellacorte.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.felicedellacorte.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.felicedellacorte.com\/index.php\/wp-json\/wp\/v2\/comments?post=41"}],"version-history":[{"count":2,"href":"http:\/\/www.felicedellacorte.com\/index.php\/wp-json\/wp\/v2\/posts\/41\/revisions"}],"predecessor-version":[{"id":308,"href":"http:\/\/www.felicedellacorte.com\/index.php\/wp-json\/wp\/v2\/posts\/41\/revisions\/308"}],"wp:attachment":[{"href":"http:\/\/www.felicedellacorte.com\/index.php\/wp-json\/wp\/v2\/media?parent=41"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.felicedellacorte.com\/index.php\/wp-json\/wp\/v2\/categories?post=41"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.felicedellacorte.com\/index.php\/wp-json\/wp\/v2\/tags?post=41"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}